{"id":400,"date":"2026-08-10T16:55:04","date_gmt":"2026-08-10T16:55:04","guid":{"rendered":"https:\/\/lichens.ai\/membre\/andre-en\/"},"modified":"2026-08-23T23:27:07","modified_gmt":"2026-08-23T23:27:07","slug":"andre-en","status":"publish","type":"membre","link":"https:\/\/lichens.ai\/en\/membre\/andre-en\/","title":{"rendered":"Andr\u00e9"},"excerpt":{"rendered":"<p>Always exploring: he learns, he digs, then he teaches. All of it from Mexico.<\/p>\n","protected":false},"featured_media":258,"menu_order":10,"template":"","meta":{"_acf_changed":false},"class_list":["post-400","membre","type-membre","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/membre\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/membre"}],"about":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/types\/membre"}],"version-history":[{"count":0,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/membre\/400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/media\/258"}],"wp:attachment":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/media?parent=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}