{"id":409,"date":"2026-08-10T16:55:06","date_gmt":"2026-08-10T16:55:06","guid":{"rendered":"https:\/\/lichens.ai\/membre\/gabriel-en\/"},"modified":"2026-08-23T23:27:07","modified_gmt":"2026-08-23T23:27:07","slug":"gabriel-en","status":"publish","type":"membre","link":"https:\/\/lichens.ai\/en\/membre\/gabriel-en\/","title":{"rendered":"Gabriel"},"excerpt":{"rendered":"<p>An optimization pro \u2014 he could turn a scooptram into a race car!<\/p>\n","protected":false},"featured_media":276,"menu_order":19,"template":"","meta":{"_acf_changed":false},"class_list":["post-409","membre","type-membre","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/membre\/409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/membre"}],"about":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/types\/membre"}],"version-history":[{"count":0,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/membre\/409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/media\/276"}],"wp:attachment":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/media?parent=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}