{"id":387,"date":"2026-08-13T15:16:48","date_gmt":"2026-08-13T15:16:48","guid":{"rendered":"https:\/\/lichens.ai\/spotd-2\/events\/"},"modified":"2026-08-17T01:04:27","modified_gmt":"2026-08-17T01:04:27","slug":"events","status":"publish","type":"page","link":"https:\/\/lichens.ai\/en\/spotd\/events\/","title":{"rendered":"Spotd \u00b7 Events"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":383,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-387","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/pages\/387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/comments?post=387"}],"version-history":[{"count":1,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/pages\/387\/revisions"}],"predecessor-version":[{"id":458,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/pages\/387\/revisions\/458"}],"up":[{"embeddable":true,"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/pages\/383"}],"wp:attachment":[{"href":"https:\/\/lichens.ai\/en\/wp-json\/wp\/v2\/media?parent=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}